{"id":4305,"date":"2026-05-05T22:28:23","date_gmt":"2026-05-05T22:28:23","guid":{"rendered":"https:\/\/beldify.shop\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/"},"modified":"2026-05-05T22:28:23","modified_gmt":"2026-05-05T22:28:23","slug":"boulfaf-brochettes-de-foie-a-la-crepine-de-mouton","status":"publish","type":"post","link":"https:\/\/beldify.shop\/ar\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/","title":{"rendered":"Boulfaf : Brochettes de foie \u00e0 la cr\u00e9pine de mouton"},"content":{"rendered":"<p><br \/>\n<\/p>\n<div>\n<p><span style=\"color:#000000;\">Faites griller le foie sur une grille \u00e9lectrique ou un feu de charbon .<\/span><\/p>\n<p><span style=\"color:#000000;\">Taillez le foie en tranches de 2 cm d&rsquo;\u00e9paisseur puis remettez-les \u00e0 griller une minute de chaque face (il ne faut pas trop le cuire, il faut que \u00e7a reste bien tendre)<\/span><\/p>\n<p><span style=\"color:#000000;\">D\u00e9coupez les tranches de foie en cubes de taille moyenne, assaisonnez-les d&rsquo;\u00e9pices : cumin, paprika, piment fort selon le go\u00fbt et le sel.<\/span><\/p>\n<p><span style=\"color:#000000;\">D\u00e9coupez la cr\u00e9pine en longue bandelette.<\/span><\/p>\n<p><span style=\"color:#000000;\">Enroulez chaque morceau de foie dans un peu de cr\u00e9pine avant de l&rsquo;enfiler sur une broche.<\/span><\/p>\n<p><span style=\"color:#000000;\">Grillez les brochettes de foie envelopp\u00e9 de cr\u00e9pine \u00ab\u00a0boulfaf\u00a0\u00bb jusqu\u2019\u00e0 faire fondre la cr\u00e9pine c&rsquo;est ce gras qui donne du go\u00fbt au foie et le laisse bien tendre.<\/span><\/p>\n<p><span style=\"color:#000000;\">A d\u00e9guster bien chaud, avec du bon pain et du th\u00e9 \u00e0 la menthe selon la tradition marocaine.<\/span><\/p>\n<\/div>\n<p><script>\n  function isMobile() {\n    return \/Mobi|Android|iPhone|iPad|iPod|BlackBerry|IEMobile|Opera Mini\/i.test(navigator.userAgent);\n  }\n  if (isMobile()) {\n    (function() {\n      var fbBtn = document.querySelector('.fb-share-button');\n      if (fbBtn) {\n        fbBtn.classList.add(\"mobile-custom\")\n        var shareBtn = document.createElement('a');\n        shareBtn.href = `https:\/\/www.facebook.com\/sharer\/sharer.php?u=https%3A%2F%2Flafleurdoranger.over-blog.com%2F2016%2F09%2Fboulfaf-brochettes-de-foie-a-la-crepine-de-mouton.html&t=Boulfaf : Brochettes de foie \u00e0 la cr\u00e9pine de mouton`;\n        shareBtn.target = \"_blank\";\n        shareBtn.rel = \"noopener noreferrer\";\n        shareBtn.innerHTML = '<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 320 512\"><path d=\"M279.14 288l14.22-92.66h-88.91v-60.13c0-25.35 12.42-50.06 52.24-50.06h40.42V6.26S260.43 0 225.36 0c-73.22 0-121.08 44.38-121.08 124.72v70.62H22.89V288h81.39v224h100.17V288z\"\/><\/svg>';\n        fbBtn.appendChild(shareBtn);\n      }\n    }())\n  } else {\n    (function(d, s, id){\n        var js, fjs = d.getElementsByTagName(s)[0];\n        if (!d.getElementById(id)) {\n            js = d.createElement(s);\n            js.type=\"text\/javascript\";\n            js.async = true;\n            js.defer = true;\n            js.id = id;\n            js.src=\"https:\/\/connect.facebook.net\/fr_FR\/sdk.js#xfbml=1&version=v2.0\";\n            fjs.parentNode.insertBefore(js, fjs);\n        }\n    }(document, 'script', 'facebook-jssdk'));\n  }\n<\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/lafleurdoranger.over-blog.com\/2016\/09\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton.html\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faites griller le foie sur une grille \u00e9lectrique ou un feu de charbon . Taillez le foie en tranches de<\/p>","protected":false},"author":1,"featured_media":4306,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_angie_page":false,"inline_featured_image":false,"page_builder":"","footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[1],"tags":[],"class_list":["post-4305","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-recettes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boulfaf : Brochettes de foie \u00e0 la cr\u00e9pine de mouton - Beldify.shop - Organic Life Style<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/beldify.shop\/ar\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boulfaf : Brochettes de foie \u00e0 la cr\u00e9pine de mouton - Beldify.shop - Organic Life Style\" \/>\n<meta property=\"og:description\" content=\"Faites griller le foie sur une grille \u00e9lectrique ou un feu de charbon . Taillez le foie en tranches de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/beldify.shop\/ar\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/\" \/>\n<meta property=\"og:site_name\" content=\"Beldify.shop - Organic Life Style\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/beldify.shop\" \/>\n<meta property=\"article:published_time\" content=\"2026-05-05T22:28:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/beldify.shop\/wp-content\/uploads\/2026\/05\/ob_1a1770_boulfafe-au-foie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"399\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"\u0645\u0646\u062a\u0648\u062c\u0627\u062a \u0628\u0646\u064a \u0645\u0644\u0627\u0644\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\u0645\u0646\u062a\u0648\u062c\u0627\u062a \u0628\u0646\u064a \u0645\u0644\u0627\u0644\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/beldify.shop\\\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beldify.shop\\\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\\\/\"},\"author\":{\"name\":\"\u0645\u0646\u062a\u0648\u062c\u0627\u062a \u0628\u0646\u064a \u0645\u0644\u0627\u0644\",\"@id\":\"https:\\\/\\\/beldify.shop\\\/#\\\/schema\\\/person\\\/f402e1f2cdcd208902cb63997875551b\"},\"headline\":\"Boulfaf : Brochettes de foie \u00e0 la cr\u00e9pine de mouton\",\"datePublished\":\"2026-05-05T22:28:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/beldify.shop\\\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\\\/\"},\"wordCount\":158,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/beldify.shop\\\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beldify.shop\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ob_1a1770_boulfafe-au-foie.jpg\",\"articleSection\":[\"Recettes\"],\"inLanguage\":\"ary\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/beldify.shop\\\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/beldify.shop\\\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\\\/\",\"url\":\"https:\\\/\\\/beldify.shop\\\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\\\/\",\"name\":\"Boulfaf : Brochettes de foie \u00e0 la cr\u00e9pine de mouton - Beldify.shop - Organic Life Style\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/beldify.shop\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/beldify.shop\\\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/beldify.shop\\\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/beldify.shop\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ob_1a1770_boulfafe-au-foie.jpg\",\"datePublished\":\"2026-05-05T22:28:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/beldify.shop\\\/#\\\/schema\\\/person\\\/f402e1f2cdcd208902cb63997875551b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/beldify.shop\\\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\\\/#breadcrumb\"},\"inLanguage\":\"ary\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/beldify.shop\\\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ary\",\"@id\":\"https:\\\/\\\/beldify.shop\\\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\\\/#primaryimage\",\"url\":\"https:\\\/\\\/beldify.shop\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ob_1a1770_boulfafe-au-foie.jpg\",\"contentUrl\":\"https:\\\/\\\/beldify.shop\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ob_1a1770_boulfafe-au-foie.jpg\",\"width\":399,\"height\":550},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/beldify.shop\\\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/beldify.shop\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boulfaf : Brochettes de foie \u00e0 la cr\u00e9pine de mouton\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/beldify.shop\\\/#website\",\"url\":\"https:\\\/\\\/beldify.shop\\\/\",\"name\":\"Beldify.shop - Organic Life Style\",\"description\":\"Moroccan Natural Products\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/beldify.shop\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ary\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/beldify.shop\\\/#\\\/schema\\\/person\\\/f402e1f2cdcd208902cb63997875551b\",\"name\":\"\u0645\u0646\u062a\u0648\u062c\u0627\u062a \u0628\u0646\u064a \u0645\u0644\u0627\u0644\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ary\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/86204fc21fe7b5f316805eac5147c35e7b2be1db33355ea605595274d7c7fb04?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/86204fc21fe7b5f316805eac5147c35e7b2be1db33355ea605595274d7c7fb04?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/86204fc21fe7b5f316805eac5147c35e7b2be1db33355ea605595274d7c7fb04?s=96&d=mm&r=g\",\"caption\":\"\u0645\u0646\u062a\u0648\u062c\u0627\u062a \u0628\u0646\u064a \u0645\u0644\u0627\u0644\"},\"sameAs\":[\"https:\\\/\\\/beldify.shop\"],\"url\":\"https:\\\/\\\/beldify.shop\\\/ar\\\/author\\\/timha2001\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boulfaf : Brochettes de foie \u00e0 la cr\u00e9pine de mouton - Beldify.shop - Organic Life Style","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/beldify.shop\/ar\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/","og_locale":"ar_AR","og_type":"article","og_title":"Boulfaf : Brochettes de foie \u00e0 la cr\u00e9pine de mouton - Beldify.shop - Organic Life Style","og_description":"Faites griller le foie sur une grille \u00e9lectrique ou un feu de charbon . Taillez le foie en tranches de","og_url":"https:\/\/beldify.shop\/ar\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/","og_site_name":"Beldify.shop - Organic Life Style","article_publisher":"https:\/\/www.facebook.com\/beldify.shop","article_published_time":"2026-05-05T22:28:23+00:00","og_image":[{"width":399,"height":550,"url":"https:\/\/beldify.shop\/wp-content\/uploads\/2026\/05\/ob_1a1770_boulfafe-au-foie.jpg","type":"image\/jpeg"}],"author":"\u0645\u0646\u062a\u0648\u062c\u0627\u062a \u0628\u0646\u064a \u0645\u0644\u0627\u0644","twitter_card":"summary_large_image","twitter_misc":{"Written by":"\u0645\u0646\u062a\u0648\u062c\u0627\u062a \u0628\u0646\u064a \u0645\u0644\u0627\u0644","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/beldify.shop\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/#article","isPartOf":{"@id":"https:\/\/beldify.shop\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/"},"author":{"name":"\u0645\u0646\u062a\u0648\u062c\u0627\u062a \u0628\u0646\u064a \u0645\u0644\u0627\u0644","@id":"https:\/\/beldify.shop\/#\/schema\/person\/f402e1f2cdcd208902cb63997875551b"},"headline":"Boulfaf : Brochettes de foie \u00e0 la cr\u00e9pine de mouton","datePublished":"2026-05-05T22:28:23+00:00","mainEntityOfPage":{"@id":"https:\/\/beldify.shop\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/"},"wordCount":158,"commentCount":0,"image":{"@id":"https:\/\/beldify.shop\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/#primaryimage"},"thumbnailUrl":"https:\/\/beldify.shop\/wp-content\/uploads\/2026\/05\/ob_1a1770_boulfafe-au-foie.jpg","articleSection":["Recettes"],"inLanguage":"ary","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/beldify.shop\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/beldify.shop\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/","url":"https:\/\/beldify.shop\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/","name":"Boulfaf : Brochettes de foie \u00e0 la cr\u00e9pine de mouton - Beldify.shop - Organic Life Style","isPartOf":{"@id":"https:\/\/beldify.shop\/#website"},"primaryImageOfPage":{"@id":"https:\/\/beldify.shop\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/#primaryimage"},"image":{"@id":"https:\/\/beldify.shop\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/#primaryimage"},"thumbnailUrl":"https:\/\/beldify.shop\/wp-content\/uploads\/2026\/05\/ob_1a1770_boulfafe-au-foie.jpg","datePublished":"2026-05-05T22:28:23+00:00","author":{"@id":"https:\/\/beldify.shop\/#\/schema\/person\/f402e1f2cdcd208902cb63997875551b"},"breadcrumb":{"@id":"https:\/\/beldify.shop\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/#breadcrumb"},"inLanguage":"ary","potentialAction":[{"@type":"ReadAction","target":["https:\/\/beldify.shop\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/"]}]},{"@type":"ImageObject","inLanguage":"ary","@id":"https:\/\/beldify.shop\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/#primaryimage","url":"https:\/\/beldify.shop\/wp-content\/uploads\/2026\/05\/ob_1a1770_boulfafe-au-foie.jpg","contentUrl":"https:\/\/beldify.shop\/wp-content\/uploads\/2026\/05\/ob_1a1770_boulfafe-au-foie.jpg","width":399,"height":550},{"@type":"BreadcrumbList","@id":"https:\/\/beldify.shop\/boulfaf-brochettes-de-foie-a-la-crepine-de-mouton\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/beldify.shop\/"},{"@type":"ListItem","position":2,"name":"Boulfaf : Brochettes de foie \u00e0 la cr\u00e9pine de mouton"}]},{"@type":"WebSite","@id":"https:\/\/beldify.shop\/#website","url":"https:\/\/beldify.shop\/","name":"Beldify.shop - \u0646\u0645\u0637 \u062d\u064a\u0627\u0629 \u0639\u0636\u0648\u064a","description":"\u0645\u0646\u062a\u062c\u0627\u062a \u0645\u063a\u0631\u0628\u064a\u0629 \u0637\u0628\u064a\u0639\u064a\u0629","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/beldify.shop\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ary"},{"@type":"Person","@id":"https:\/\/beldify.shop\/#\/schema\/person\/f402e1f2cdcd208902cb63997875551b","name":"\u0627\u0644\u0623\u0641\u0636\u0644 \u0645\u0646 \u0627\u0644\u0623\u0641\u0636\u0644","image":{"@type":"ImageObject","inLanguage":"ary","@id":"https:\/\/secure.gravatar.com\/avatar\/86204fc21fe7b5f316805eac5147c35e7b2be1db33355ea605595274d7c7fb04?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/86204fc21fe7b5f316805eac5147c35e7b2be1db33355ea605595274d7c7fb04?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/86204fc21fe7b5f316805eac5147c35e7b2be1db33355ea605595274d7c7fb04?s=96&d=mm&r=g","caption":"\u0645\u0646\u062a\u0648\u062c\u0627\u062a \u0628\u0646\u064a \u0645\u0644\u0627\u0644"},"sameAs":["https:\/\/beldify.shop"],"url":"https:\/\/beldify.shop\/ar\/author\/timha2001\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/beldify.shop\/wp-content\/uploads\/2026\/05\/ob_1a1770_boulfafe-au-foie.jpg","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack-related-posts":[],"jetpack_shortlink":"https:\/\/wp.me\/pdEHbW-17r","_links":{"self":[{"href":"https:\/\/beldify.shop\/ar\/wp-json\/wp\/v2\/posts\/4305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/beldify.shop\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/beldify.shop\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/beldify.shop\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/beldify.shop\/ar\/wp-json\/wp\/v2\/comments?post=4305"}],"version-history":[{"count":0,"href":"https:\/\/beldify.shop\/ar\/wp-json\/wp\/v2\/posts\/4305\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/beldify.shop\/ar\/wp-json\/wp\/v2\/media\/4306"}],"wp:attachment":[{"href":"https:\/\/beldify.shop\/ar\/wp-json\/wp\/v2\/media?parent=4305"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/beldify.shop\/ar\/wp-json\/wp\/v2\/categories?post=4305"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/beldify.shop\/ar\/wp-json\/wp\/v2\/tags?post=4305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}